{"id":33825,"date":"2024-06-14T08:02:56","date_gmt":"2024-06-14T13:02:56","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=33825"},"modified":"2024-06-14T08:02:56","modified_gmt":"2024-06-14T13:02:56","slug":"suben-calificacion-al-municipio-de-chalco","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/06\/14\/suben-calificacion-al-municipio-de-chalco\/","title":{"rendered":"Suben calificaci\u00f3n al municipio de Chalco"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">El municipio presenta condiciones limitadas en los indicadores de pobreza multidimensional.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">HR Ratings revis\u00f3 al alza la calificaci\u00f3n de \u201cHR BBB+\u201d a \u201cHR A-\u201d y mantuvo la perspectiva Estable al municipio de Chalco, Estado de M\u00e9xico.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">De acuerdo con un reporte enviado a la Bolsa Mexicana de Valores, la revisi\u00f3n al alza de la calificaci\u00f3n obedece a la reducci\u00f3n observada y estimada en las m\u00e9tricas de endeudamiento relativo.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al cierre del 2023 se report\u00f3 un super\u00e1vit en el balance primario (BP) de 13.6% de los ingresos totales (IT), como resultado de un crecimiento en las participaciones federales, as\u00ed como de ingresos propios, lo que result\u00f3 en un alza de 13.9% en los Ingresos de Libre Disposici\u00f3n (ILD).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Derivado de lo anterior, el municipio registr\u00f3 un elevado nivel de liquidez, lo que le permiti\u00f3 no hacer uso de financiamiento de corto plazo, contrario a lo estimado por HR Ratings en la revisi\u00f3n anterior.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Con ello, la m\u00e9trica de deuda neta (DN) disminuy\u00f3 de 19.9% a 13.4% de forma interanual, nivel inferior al esperado anteriormente de 24.0%. Por otro lado, el pasivo circulante (PC) ascendi\u00f3 a 12.0% de los ILD derivado del aumento reportado en la cuenta de Contratistas, por lo que este resultado fue superior al 5.1% proyectado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Asimismo, \u201cpara el 2024 se espera un d\u00e9ficit en el BP de 5.7%, debido a un aumento estimado el cap\u00edtulo de Inversi\u00f3n P\u00fablica financiado a trav\u00e9s de la liquidez reportada al cierre del ejercicio. No obstante, se espera que entre el 2025 y el 2026 se reporte un super\u00e1vit en el BP de 0.2% promedio asociado a una reducci\u00f3n en el gasto en Obra P\u00fablica, sumado a la expectativa de se mantenga una tendencia positiva en los ILD\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Para los pr\u00f3ximos a\u00f1os no se estima el uso de financiamiento de corto plazo, por lo que se reportar\u00eda un nivel de DN promedio de 12.9%, mientras que el PC reportar\u00eda un promedio de 14.5 por ciento.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Reducci\u00f3n del nivel de endeudamiento<\/span><br \/>\n<span style=\"font-size: 14pt;\">HR Ratings destaca que la deuda directa del municipio ascendi\u00f3 a 152.6 millones de pesos al cierre del 2023, y est\u00e1 compuesta por un cr\u00e9dito estructurado con Banobras, a trav\u00e9s del programa especial FEFOM, con un saldo de 132.7 millones y por un convenio de pago con el ISSEMyM por 19.9 millones.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El factor Social es considerado limitado debido a que el municipio presenta condiciones limitadas en los indicadores de pobreza multidimensional al registrar un porcentaje de poblaci\u00f3n en condici\u00f3n de pobreza superior al nivel nacional.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por su parte, los factores Ambiental y de Gobernanza son considerados promedio. Respecto al factor ambiental, se cuenta con una vulnerabilidad moderada al cambio clim\u00e1tico y no se identifican contingencias asociadas con sus servicios de agua y basura. El factor gobernanza cumple con lineamientos de transparencia y armonizaci\u00f3n contable y no se identifican contingencias significativas relacionadas con juicios laborales o mercantiles.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El municipio presenta condiciones limitadas en los indicadores de pobreza multidimensional. HR Ratings revis\u00f3 al alza la calificaci\u00f3n de \u201cHR BBB+\u201d a \u201cHR A-\u201d y mantuvo la perspectiva Estable al municipio de Chalco, Estado de M\u00e9xico. De acuerdo con un reporte enviado a la Bolsa Mexicana de Valores, la revisi\u00f3n al alza de la calificaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":33826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-33825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:16:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/06\/F7VOU4BDRVEBJGGHVUDCH3VVTI.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/33825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=33825"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/33825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/33826"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=33825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=33825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=33825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}