{"id":32410,"date":"2024-05-27T01:58:00","date_gmt":"2024-05-27T06:58:00","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=32410"},"modified":"2024-05-27T01:58:00","modified_gmt":"2024-05-27T06:58:00","slug":"queretaro-estalla-pirotecnia-almacenada-en-sacristia-de-iglesia","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/05\/27\/queretaro-estalla-pirotecnia-almacenada-en-sacristia-de-iglesia\/","title":{"rendered":"Quer\u00e9taro: estalla pirotecnia almacenada en sacrist\u00eda de iglesia"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Este domingo se registr\u00f3 una explosi\u00f3n e incendio en una bodega localizada de pirotecnia ubicada en las inmediaciones de un capilla en la colonia Los Sauces de la capital queretana.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El incendio se produjo en una habitaci\u00f3n de la sacrist\u00eda (lugar sacerdotes guardan ornamentos y otras cosas pertenecientes al culto) ubicada afuera de la parroquia de la Divina Providencia, de la colonia Los Sauces.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Afuera del templo se realizaban actividades como parte de la fiesta patronal, cuando por causas desconocidas se produjo un estallido que hizo volar el techo del inmueble.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Bomberos y elementos de Protecci\u00f3n Civil del municipio de Quer\u00e9taro se presentaron de inmediato en el lugar y apagaron el fuego.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">A consecuencia de la explosi\u00f3n y que la mayordom\u00eda de la iglesia pretend\u00eda quemar un castillo sin tener los permisos correspondientes ni cubrir las medidas de seguridad, la direcci\u00f3n de Protecci\u00f3n Civil decret\u00f3 la suspensi\u00f3n temporal de actividades religiosas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El s\u00e1bado la misma direcci\u00f3n de Protecci\u00f3n Civil del municipio de Quer\u00e9taro asegur\u00f3 pirotecnia que se pretend\u00eda quemar en la fiesta patronal de la Delegaci\u00f3n de Santa Rosa J\u00e1uregui.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">De acuerdo a la dependencia,el decomiso fue por no contar con los permisos correspondientes para quemarlos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo se registr\u00f3 una explosi\u00f3n e incendio en una bodega localizada de pirotecnia ubicada en las inmediaciones de un capilla en la colonia Los Sauces de la capital queretana. El incendio se produjo en una habitaci\u00f3n de la sacrist\u00eda (lugar sacerdotes guardan ornamentos y otras cosas pertenecientes al culto) ubicada afuera de la parroquia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":32411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-32410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-08 20:04:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/05\/piro.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/32410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=32410"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/32410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/32411"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=32410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=32410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=32410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}