{"id":28072,"date":"2024-03-19T08:16:05","date_gmt":"2024-03-19T14:16:05","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=28072"},"modified":"2024-03-19T08:16:05","modified_gmt":"2024-03-19T14:16:05","slug":"respalda-cardenas-proyecto-energetico-de-sheinbaum","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/03\/19\/respalda-cardenas-proyecto-energetico-de-sheinbaum\/","title":{"rendered":"Respalda C\u00e1rdenas proyecto energ\u00e9tico de Sheinbaum"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Cuauht\u00e9moc C\u00e1rdenas respald\u00f3 la pol\u00edtica energ\u00e9tica anunciada por la candidata presidencial de Morena, Claudia Sheinbaum.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Luego de hacer una guardia de honor en el Monumento a la Revoluci\u00f3n, donde yacen los restos de su padre L\u00e1zaro C\u00e1rdenas, en ocasi\u00f3n del 86 aniversario de la expropiaci\u00f3n petrolera, destac\u00f3 la necesidad de dar autonom\u00eda de gesti\u00f3n y financiera a Petr\u00f3leos Mexicanos, as\u00ed como sanear sus finanzas e impulsar la petroqu\u00edmica.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">C\u00e1rdenas acompa\u00f1\u00f3 a Sheinbaum en la presentaci\u00f3n de su pol\u00edtica energ\u00e9tica, la cual se realiz\u00f3 en el monumento a la Revoluci\u00f3n. Esta es la primera vez que el fundador del PRD aparece en un evento p\u00fablico junto a la abanderada morenista.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La aspirante presidencial pidi\u00f3 la asesor\u00eda del michoacano en temas energ\u00e9ticos y expuso que le presentar\u00e1 ideas al respecto.\u00a0<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Cuando se le pregunt\u00f3 si Sheinbaum es la mejor opci\u00f3n para el pa\u00eds, respondi\u00f3 que eso lo dir\u00e1n los mexicanos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuauht\u00e9moc C\u00e1rdenas respald\u00f3 la pol\u00edtica energ\u00e9tica anunciada por la candidata presidencial de Morena, Claudia Sheinbaum. Luego de hacer una guardia de honor en el Monumento a la Revoluci\u00f3n, donde yacen los restos de su padre L\u00e1zaro C\u00e1rdenas, en ocasi\u00f3n del 86 aniversario de la expropiaci\u00f3n petrolera, destac\u00f3 la necesidad de dar autonom\u00eda de gesti\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-28072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:23:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/03\/big_tf20u.jpeg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/28072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=28072"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/28072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/28073"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=28072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=28072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=28072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}