{"id":28011,"date":"2024-03-18T10:08:12","date_gmt":"2024-03-18T16:08:12","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=28011"},"modified":"2024-03-18T10:08:12","modified_gmt":"2024-03-18T16:08:12","slug":"cndh-senala-intento-de-censura-tras-acusaciones-del-pan","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/03\/18\/cndh-senala-intento-de-censura-tras-acusaciones-del-pan\/","title":{"rendered":"CNDH se\u00f1ala intento de censura tras acusaciones del PAN"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">La Comisi\u00f3n Nacional de los Derechos Humanos (CNDH) se\u00f1al\u00f3 que se le pretende censurar por emitir su informe sobre violencia pol\u00edtica. Dijo que ha recibido sendos requerimientos del Instituto Nacional Electoral (INE) y del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) derivados de dos denuncias del Partido Acci\u00f3n Nacional (PAN) que pretenden cuestionar su misi\u00f3n como m\u00e1ximo organismo protector de los derechos humanos en el pa\u00eds.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Apunt\u00f3 que el argumento central es que con la emisi\u00f3n de su Informe sobre Violencia Pol\u00edtica para la Protecci\u00f3n y Defensa del Derecho a la Democracia, esta CNDH se est\u00e1 entrometiendo en el proceso electoral.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En un comunicado detall\u00f3 que \u201cesta pretensi\u00f3n de silenciar a la CNDH ser\u00eda un peligroso precedente, pues como hemos dicho y reiterado, la creaci\u00f3n del Mecanismo Nacional de Observaci\u00f3n y Protecci\u00f3n del Derecho a la Democracia, para el seguimiento del Pronunciamiento de la CNDH sobre el deber de<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">prevenir y erradicar las diversas manifestaciones de Violencia Pol\u00edtica en el contexto del ejercicio de los derechos pol\u00edtico-electorales, publicado en diciembre de 2023, no busca en lo m\u00e1s m\u00ednimo influir en las decisiones de las autoridades electorales, mucho menos orientar el voto, como se ha se\u00f1alado de manera tendenciosa\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por ello, rechaz\u00f3 categ\u00f3ricamente que, \u201ccon la emisi\u00f3n de sus Informes sobre Violencia Pol\u00edtica hubiera violentado el mandato que le ha sido encomendado en virtud del art\u00edculo 102, apartado B de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos (CPEUM), y rechaza las aseveraciones que algunos actores partidistas hacen su en contra\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">A\u00f1adi\u00f3 que no es la primera ocasi\u00f3n que se intenta descalificar y callar a la CNDH; pero censurar y mutilarle una de las funciones sustantivas, a trav\u00e9s ya no s\u00f3lo de campa\u00f1as medi\u00e1ticas sino de la utilizaci\u00f3n pol\u00edtica ahora de instancias y recursos judiciales y parajudiciales, por el siempre hecho de emitir informes que tiene la obligaci\u00f3n de realizar, muestra y alerta al pueblo de M\u00e9xico y a las mismas autoridades, sobre las pr\u00e1cticas de violencia pol\u00edtica que se dan en el marco de la contienda electoral.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cEn lo que s\u00ed debe estarse ocupando la autoridad electoral, m\u00e1s que en perseguir y amenazar a esta Comisi\u00f3n Nacional, es en actuar frente a los discursos de odio y la propaganda negra que limitan y obstaculizan el ejercicio de los derechos pol\u00edtico-electorales del pueblo, y pueden constituir un atentado contra el derecho a la democracia\u201d.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Nacional de los Derechos Humanos (CNDH) se\u00f1al\u00f3 que se le pretende censurar por emitir su informe sobre violencia pol\u00edtica. Dijo que ha recibido sendos requerimientos del Instituto Nacional Electoral (INE) y del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) derivados de dos denuncias del Partido Acci\u00f3n Nacional (PAN) que pretenden cuestionar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[1634,66,74,106],"class_list":["post-28011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-cndh","tag-ine","tag-pan","tag-tepjf"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:04:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/03\/INE-mujeres2.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/28011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=28011"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/28011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/28012"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=28011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=28011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=28011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}