{"id":17132,"date":"2023-07-04T05:30:46","date_gmt":"2023-07-04T10:30:46","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=17132"},"modified":"2023-07-04T08:43:24","modified_gmt":"2023-07-04T13:43:24","slug":"ebrard-regresar-al-redil","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2023\/07\/04\/ebrard-regresar-al-redil\/","title":{"rendered":"Ebrard, regresar al redil"},"content":{"rendered":"<p class=\"p1\">\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Por Jos\u00e9 Garc\u00eda S\u00e1nchez<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Para nadie es un secreto que el precandidato m\u00e1s alejado de la 4T y del propio Presidente de M\u00e9xico es Marcelo Ebrard. En este momento tiene dos motivos para transformar su visi\u00f3n y proyectos, con el riesgo de perder simpatizantes que lo siguen precisamente por su lejan\u00eda al proyecto obradorista.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Aunque el ex secretario diga que seguir\u00e1 con las transformaciones, lo cierto es que los hechos lo desmienten, porque su posici\u00f3n, raigambre y proyecto pareciera tener pocas ra\u00edces populares. Por ejemplo, nadie lo imagina en Pochutla, Oaxaca, ensuci\u00e1ndose los zapatos.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Ebrard, desde un principio estuvo inconforme con todo, desde la exigencia de piso parejo que intent\u00f3 convertir en consigna y qued\u00f3 s\u00f3lo en canto pla\u00f1idero que acusaba desesperaci\u00f3n por no subir en las encuestas, hasta la exigencia de que ninguno de sus cinco compa\u00f1eros, se excediera en los gastos cuando los ingresos a las asociaciones a su alrededor, provienen hasta del extranjero.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Desde el principio la inconformidad con las reglas y las condiciones de Morena, acordados por todos los precandidatos, parecieran quedarle chicas a Ebrard, porque nunca ha dejado de advertir a sus contrincantes que deben portarse bien o de pedir, a la c\u00fapula de su partido, condiciones de competencia como el debate, que en estos momentos se convierte en un peligro de divisi\u00f3n en morena\u00a0\u00a0a causa de personajes que, como \u00e9l, mandas telegramas de inconformidad a los partidos de oposici\u00f3n, para ver si puede entrar por la puerta de la cocina a otra organizaci\u00f3n.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Atr\u00e1s quedaron los d\u00edas en los que ped\u00eda abrir las precampa\u00f1as al financiamiento privado, porque sus avanzadas en algunos estados del pa\u00eds no cuentan con dinero para seguir el proyecto ebradorista, aunque \u00e9l gaste millones con la contrataci\u00f3n de asesores extranjeros de dudosa salud mental, como es el caso del ecuatorianos Jaime Dur\u00e1n barba, quien ha asesorado a personajes de la derecha latinoamericana como el argentino Mauricio Macri o a su paisano Guillermo Lacalle, ambos con problemas judiciales por corruptos.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21850 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2023\/07\/P-MARCELO-EBRARD-JAIME-DURAN-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #e42d33;\"><strong>Dur\u00e1n Barba es un antiguo cliente de Ebrard porque lo contrat\u00f3 cuando era jefe de gobierno. Entre los clientes del licenciado en filosof\u00eda Dur\u00e1n, se cuenta a Pablo Escobar Gaviria, a cuyo partido, Alternativa Liberal, asesoraba hasta el momento de ser detenido en 1998.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Dur\u00e1n fue secretario de Administraci\u00f3n p\u00fabica en su pa\u00eds, durante la presidencia de Jamil Mahuad, pr\u00f3fugo de la justicia por peculado y corrupci\u00f3n.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>La tendencia del exsecretario de Relaciones Exteriores aceptar entrevistas en los medios cuyos conductores han atacado con <em>Fake News<\/em> a la 4T habla, por s\u00ed mismo de una fragilidad ideol\u00f3gica que mueve a pensar en que el pasado puede regresar a M\u00e9xico, sobre todo en cuanto al criminal subsidio a los medios para disfrazar problemas y crear fantas\u00edas sobre el bienestar com\u00fan.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Para explicar su lugar en el espacio pol\u00edtico sus simpatizantes cuestionan a Claudia y a Ad\u00e1n de copiar los proyectos de L\u00f3pez Obrador, cuando esa es la esencia del movimiento, as\u00ed aclaran plenamente la posici\u00f3n conservadora que enarbolan para que nadie se llame a sorpresa con cambios radicales a la pol\u00edtica actual. La campa\u00f1a de Ebrard es muy parecida a la de la derecha actualmente, radica en resaltar los defectos del contrincante en lugar de ponderar las virtudes propias. Descalificar en lugar de proponer.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Las relaciones cercanas de Ebrard, as\u00ed como sus adherentes espont\u00e1neos lo colocan como un personaje que busca, sin ideolog\u00eda ni corriente pol\u00edtica que lo identifique, la Presidencia dela rep\u00fablica. Su cercan\u00eda con el indefinido Monreal es evidente, los apoyos pe personajes como Rosario Robles, Sandra Cuevas, o Ricardo Mej\u00eda Berdeja lo aleja de un pensamiento antineoliberal que puede acarrear consecuencias serias ala pa\u00eds, sobre todo romper la continuidad de un proyecto social, que si bien encabez\u00f3 L\u00f3pez Obrador, la mayor\u00eda de los mexicanos apoya.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">S\u00f3lo a quien no va ganando en las encuestas asegura, con tanta timidez, que est\u00e1 en primer lugar, sin ning\u00fan sonrojo y sin que nadie le preguntara c\u00f3mo va en las encuestas, antepone a cualquier respuesta a los medios que es el puntero cuando la realidad es muy diferente. Porque de ser as\u00ed no lo dir\u00eda \u00e9l sino todos los dem\u00e1s. Ebrard advirti\u00f3 de manera prepotente que si le hacen una \u201cchicanada\u201d se sale de Morena. Es decir, si no gana se va, pues que vaya eligiendo partido, con quienes se identifica cada d\u00eda m\u00e1s.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt; color: #e42d33;\"><strong>No hay juego limpio en la precandidatura de Ebrard, por lo menos as\u00ed lo muestran quienes organizan avanzadas para colocarlo en la c\u00faspide del poder, porque en este caso no se trata de darle un leve giro al proyecto, una profundizaci\u00f3n, una ampliaci\u00f3n, sino un rechazo a todo lo hecho por su antecesor.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Es momento de escuchar a la gente, de saber si es necesario regresar al redil o saltarse las trancas.<\/span><\/p>\n<div><\/div>\n<div><\/div>\n<div>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt;\"><strong>Twitter:\u00a0<a href=\"https:\/\/twitter.com\/Josangasa3\">@Josangasa3<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11449\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-1024x125.png\" alt=\"\" width=\"1000\" height=\"122\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-1024x125.png 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-300x37.png 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-768x94.png 768w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-1536x188.png 1536w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2023\/01\/FIRMA-EDITORIAL-NV-2048x250.png 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Por Jos\u00e9 Garc\u00eda S\u00e1nchez Para nadie es un secreto que el precandidato m\u00e1s alejado de la 4T y del<\/p>\n","protected":false},"author":4,"featured_media":3183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[2784,499,84],"class_list":["post-17132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas","tag-jaime-duran-barba","tag-marcelo-ebrard","tag-morena"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2022\/04\/NV-JOSE\u0301-GARCI\u0301A.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 00:04:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/17132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=17132"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/17132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/3183"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=17132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=17132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=17132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}